{"id":265176,"date":"2017-05-31T10:31:49","date_gmt":"2017-05-31T14:31:49","guid":{"rendered":"https:\/\/policyoptions.irpp.org\/issues\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/"},"modified":"2025-10-07T21:38:00","modified_gmt":"2025-10-08T01:38:00","slug":"pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale","status":"publish","type":"issues","link":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/","title":{"rendered":"Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale"},"content":{"rendered":"<p>Le Canada est \u00e0 la crois\u00e9e des chemins\u00a0: sa prosp\u00e9rit\u00e9 d\u00e9pend des \u00e9changes et des investissements internationaux alors que de nouvelles r\u00e9alit\u00e9s mondiales l\u2019obligent \u00e0 repenser ses orientations de longue date dans ces deux domaines cl\u00e9s. Une nouvelle approche est d\u2019autant plus importante qu\u2019une menace existentielle plane sur le syst\u00e8me commercial international depuis l\u2019\u00e9lection de Donald Trump, qui se dit d\u00e9termin\u00e9 \u00e0 chambouler la politique commerciale de son pays pour donner \u00ab\u00a0priorit\u00e9 aux \u00c9tats-Unis\u00a0\u00bb. Les tactiques de n\u00e9gociation des Am\u00e9ricains restent ind\u00e9chiffrables et leur position demeure impr\u00e9cise, mais la r\u00e9alisation de leur objectif affich\u00e9 de mettre en cause un syst\u00e8me commercial fond\u00e9 sur des r\u00e8gles aurait de s\u00e9rieuses r\u00e9percussions sur notre pays.<\/p>\n<p>H\u00e9las, les m\u00e9dias canadiens r\u00e9agissent souvent \u00e0 la situation par des pronostics \u00e0 court terme, cherchant surtout \u00e0 pr\u00e9voir ce que fera Donald Trump au jour le jour. Or nous avons d\u00e9sesp\u00e9r\u00e9ment besoin d\u2019un d\u00e9bat serein, \u00e9tay\u00e9 de donn\u00e9es probantes, pour comprendre cette conjoncture in\u00e9dite \u2014 y compris la mont\u00e9e du protectionnisme \u2014, examiner les mesures \u00e0 prendre et d\u00e9finir les priorit\u00e9s \u00e0 long terme qui nous guideront \u00e0 travers l\u2019instabilit\u00e9 actuelle. Dans la conclusion de l\u2019ouvrage collectif intitul\u00e9 <a href=\"https:\/\/irpp.org\/fr\/research\/trade\/\"><em>Redesigning Canadian Trade Policies for New Global Realities<\/em><\/a>, que l\u2019IRPP vient de publier, nous pr\u00e9sentons nos principaux r\u00e9sultats de recherche et propositions de politiques en la mati\u00e8re.<\/p>\n<p>Nos analyses montrent que l\u2019\u00e9conomie mondiale est en pleine transformation. La production, l\u2019innovation et la croissance int\u00e9rieures d\u00e9pendent \u00e0 la fois des exportations et des importations. Beaucoup d\u2019entreprises collaborent au sein de cha\u00eenes d\u2019approvisionnement mondiales au lieu de produire dans un seul pays, misant sur leurs filiales \u00e9trang\u00e8res pour servir les consommateurs d\u2019autres pays. L\u2019influence d\u00e9cisive exerc\u00e9e par des march\u00e9s \u00e9mergents comme l\u2019Inde et la Chine a fait d\u00e9placer le pouvoir \u00e9conomique et explique en partie la stagnation des n\u00e9gociations au sein de l\u2019Organisation mondiale du commerce. Et les faibles perspectives de croissance, surtout depuis la crise financi\u00e8re de 2008-2009, suscitent l\u2019inqui\u00e9tude dans plusieurs pays d\u00e9velopp\u00e9s, y compris le Canada.<\/p>\n<p>Vu la faiblesse de notre performance \u00e9conomique durant les 15\u00a0derni\u00e8res ann\u00e9es, ce contexte nous impose d\u2019adopter une approche commerciale globale et concert\u00e9e, incluant nos relations avec les \u00c9tats-Unis. Afin d\u2019aider nos d\u00e9cideurs \u00e0 privil\u00e9gier les objectifs d\u2019une politique \u00e0 long terme, m\u00eame s\u2019ils doivent aussi g\u00e9rer certains risques imm\u00e9diats, nous proposons une s\u00e9rie de mesures dans quatre domaines cl\u00e9s.<\/p>\n<p>Avant tout, le Canada doit \u00e9laborer des politiques inclusives assurant au plus grand nombre de profiter des avantages de la mondialisation et des progr\u00e8s technologiques, notamment pour pr\u00e9server le soutien public aux \u00e9changes et aux accords commerciaux. Car si les Canadiens jugent ces avantages trop concentr\u00e9s au sommet, ils r\u00e9sisteront aux mesures qui visent \u00e0 lib\u00e9raliser les \u00e9changes pour stimuler la prosp\u00e9rit\u00e9. Parmi les mesures d\u2019inclusion essentielles, citons le renforcement des filets de s\u00e9curit\u00e9 sociale pour les travailleurs dont les emplois sont menac\u00e9s par des perturbations \u00e9conomiques (li\u00e9es ou non au commerce), la formation professionnelle et le perfectionnement des comp\u00e9tences.<\/p>\n<p>En deuxi\u00e8me lieu, nous devons dynamiser les \u00e9changes et la productivit\u00e9 en facilitant, plut\u00f4t qu\u2019en entravant, la r\u00e9affectation des ressources. Face \u00e0 l\u2019\u00e9volution constante de l\u2019\u00e9conomie globale, il s\u2019agit ici d\u2019assurer la circulation souple et rapide du capital et de la main-d\u2019\u0153uvre, allant d\u2019entreprises \u00e0 faible performance \u00e0 celles qui prosp\u00e8rent.<\/p>\n<p>Troisi\u00e8mement, nous devons am\u00e9liorer la connectivit\u00e9 mondiale pour renforcer les liens de nos entreprises et travailleurs avec les partenaires et march\u00e9s internationaux. Pour ce faire, il faut lib\u00e9raliser les exportations <em>et<\/em> les importations, \u00e9laborer des proc\u00e9dures douani\u00e8res rapides et efficaces, et investir dans des infrastructures de transport et des r\u00e9seaux de communication fiables. Car la productivit\u00e9 des entreprises et des travailleurs d\u00e9pend non seulement de leur initiative mais aussi de leurs contacts, de leurs r\u00e9seaux et de leur capacit\u00e9 de travailler avec des partenaires solides, o\u00f9 qu\u2019ils se trouvent dans le monde.<\/p>\n<p>Enfin, le Canada doit jouer un r\u00f4le central dans le renforcement d\u2019un syst\u00e8me mondial d\u2019\u00e9changes et d\u2019investissements fond\u00e9 sur des r\u00e8gles. Face au caract\u00e8re mondial de la production, du commerce et des investissements, nous devons privil\u00e9gier le multilat\u00e9ralisme plut\u00f4t que d\u2019\u00e9riger un syst\u00e8me ing\u00e9rable d\u2019ententes bilat\u00e9rales qui se chevauchent. L\u2019approche multilat\u00e9rale est le meilleur moyen de resserrer nos liens avec les march\u00e9s \u00e9mergents en plein essor et de diversifier ainsi nos \u00e9changes et investissements. En clair, une puissance moyenne comme le Canada ne peut renforcer son \u00e9conomie en faisant cavalier seul.<\/p>\n<p>Ces priorit\u00e9s \u00e0 long terme doivent dicter notre strat\u00e9gie de ren\u00e9gociation de l\u2019ALENA et de pourparlers bilat\u00e9raux avec la Chine. Elles n\u00e9cessitent d\u2019adopter une politique commerciale inclusive qui facilite la r\u00e9affectation des ressources et la connectivit\u00e9 mondiale, tout en jetant les bases d\u2019un meilleur syst\u00e8me commercial international. Au-del\u00e0 de l\u2019arbre qui cache la for\u00eat, nous devons embrasser un vaste horizon en cette phase critique pour notre \u00e9conomie.<\/p>\n<p><span class=\"image-caption\">Photo:\u00a0Shutterstock\/Harvepino<\/span><\/p>\n<hr \/>\n<p><em>Souhaitez-vous r\u00e9agir \u00e0 cet article ? <\/em><em>Joignez-vous aux d\u00e9bats d\u2019<\/em>Options politiques\u00a0<em>et soumettez-nous votre texte en suivant ces\u00a0<\/em><a href=\"https:\/\/policyoptions.irpp.org\/fr\/article-submission\/\"><em>directives<\/em><\/a><em>. <\/em><em>| Do you have something to say about the article you just read? Be part of the\u00a0<\/em>Policy Options<em>\u00a0discussion, and send in your own submission.\u00a0Here is a\u00a0<\/em><a href=\"https:\/\/policyoptions.irpp.org\/article-submission\/\"><em>link<\/em><\/a><em>\u00a0on how to do it.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Canada est \u00e0 la crois\u00e9e des chemins\u00a0: sa prosp\u00e9rit\u00e9 d\u00e9pend des \u00e9changes et des investissements internationaux alors que de nouvelles r\u00e9alit\u00e9s mondiales l\u2019obligent \u00e0 repenser ses orientations de longue date dans ces deux domaines cl\u00e9s. Une nouvelle approche est d\u2019autant plus importante qu\u2019une menace existentielle plane sur le syst\u00e8me commercial international depuis l\u2019\u00e9lection de [&hellip;]<\/p>\n","protected":false},"featured_media":253581,"template":"","meta":{"_acf_changed":false,"content-type":"","ep_exclude_from_search":false,"apple_news_api_created_at":"2025-08-30T06:10:14Z","apple_news_api_id":"63bb3174-cd4c-45df-86de-1bbaab6f55fe","apple_news_api_modified_at":"2025-08-30T06:10:14Z","apple_news_api_revision":"AAAAAAAAAAD\/\/\/\/\/\/\/\/\/\/w==","apple_news_api_share_url":"https:\/\/apple.news\/AY7sxdM1MRd-G3hu6q29V_g","apple_news_cover_media_provider":"image","apple_news_coverimage":0,"apple_news_coverimage_caption":"","apple_news_cover_video_id":0,"apple_news_cover_video_url":"","apple_news_cover_embedwebvideo_url":"","apple_news_is_hidden":"","apple_news_is_paid":"","apple_news_is_preview":"","apple_news_is_sponsored":"","apple_news_maturity_rating":"","apple_news_metadata":"\"\"","apple_news_pullquote":"","apple_news_pullquote_position":"","apple_news_slug":"","apple_news_sections":[],"apple_news_suppress_video_url":false,"apple_news_use_image_component":false},"categories":[9362,9360,9372],"tags":[8407],"article-status":[],"irpp-category":[4217,4245],"section":[],"irpp-tag":[7183],"class_list":["post-265176","issues","type-issues","status-publish","has-post-thumbnail","hentry","category-economie","category-international","category-recent-stories-fr","tag-trade-fr","irpp-category-affaires-internationales","irpp-category-economie","irpp-tag-commerce"],"acf":[],"apple_news_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale\" \/>\n<meta property=\"og:description\" content=\"Le Canada est \u00e0 la crois\u00e9e des chemins\u00a0: sa prosp\u00e9rit\u00e9 d\u00e9pend des \u00e9changes et des investissements internationaux alors que de nouvelles r\u00e9alit\u00e9s mondiales l\u2019obligent \u00e0 repenser ses orientations de longue date dans ces deux domaines cl\u00e9s. Une nouvelle approche est d\u2019autant plus importante qu\u2019une menace existentielle plane sur le syst\u00e8me commercial international depuis l\u2019\u00e9lection de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/\" \/>\n<meta property=\"og:site_name\" content=\"Policy Options\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IRPP.org\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T01:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/policyoptions.irpp.org\/wp-content\/uploads\/2025\/08\/WordPress-Image-Tapp-trade-book-post-1920x672.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@irpp\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/2017\\\/05\\\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\\\/\",\"url\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/2017\\\/05\\\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\\\/\",\"name\":\"Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/2017\\\/05\\\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/2017\\\/05\\\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/policyoptions.irpp.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WordPress-Image-Tapp-trade-book-post.png\",\"datePublished\":\"2017-05-31T14:31:49+00:00\",\"dateModified\":\"2025-10-08T01:38:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/2017\\\/05\\\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/2017\\\/05\\\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/2017\\\/05\\\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/policyoptions.irpp.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WordPress-Image-Tapp-trade-book-post.png\",\"contentUrl\":\"https:\\\/\\\/policyoptions.irpp.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WordPress-Image-Tapp-trade-book-post.png\",\"width\":2000,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/2017\\\/05\\\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/policyoptions.irpp.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/\",\"name\":\"Policy Options\",\"description\":\"Institute for Research on Public Policy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/policyoptions.irpp.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/","og_locale":"fr_FR","og_type":"article","og_title":"Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale","og_description":"Le Canada est \u00e0 la crois\u00e9e des chemins\u00a0: sa prosp\u00e9rit\u00e9 d\u00e9pend des \u00e9changes et des investissements internationaux alors que de nouvelles r\u00e9alit\u00e9s mondiales l\u2019obligent \u00e0 repenser ses orientations de longue date dans ces deux domaines cl\u00e9s. Une nouvelle approche est d\u2019autant plus importante qu\u2019une menace existentielle plane sur le syst\u00e8me commercial international depuis l\u2019\u00e9lection de [&hellip;]","og_url":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/","og_site_name":"Policy Options","article_publisher":"https:\/\/www.facebook.com\/IRPP.org","article_modified_time":"2025-10-08T01:38:00+00:00","og_image":[{"width":1920,"height":672,"url":"https:\/\/policyoptions.irpp.org\/wp-content\/uploads\/2025\/08\/WordPress-Image-Tapp-trade-book-post-1920x672.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@irpp","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/","url":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/","name":"Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale","isPartOf":{"@id":"https:\/\/policyoptions.irpp.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/#primaryimage"},"image":{"@id":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/#primaryimage"},"thumbnailUrl":"https:\/\/policyoptions.irpp.org\/wp-content\/uploads\/2025\/08\/WordPress-Image-Tapp-trade-book-post.png","datePublished":"2017-05-31T14:31:49+00:00","dateModified":"2025-10-08T01:38:00+00:00","breadcrumb":{"@id":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/#primaryimage","url":"https:\/\/policyoptions.irpp.org\/wp-content\/uploads\/2025\/08\/WordPress-Image-Tapp-trade-book-post.png","contentUrl":"https:\/\/policyoptions.irpp.org\/wp-content\/uploads\/2025\/08\/WordPress-Image-Tapp-trade-book-post.png","width":2000,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/policyoptions.irpp.org\/fr\/2017\/05\/pour-une-politique-commerciale-inclusive-fondee-sur-une-approche-multilaterale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/policyoptions.irpp.org\/"},{"@type":"ListItem","position":2,"name":"Pour une politique commerciale inclusive fond\u00e9e sur une approche multilat\u00e9rale"}]},{"@type":"WebSite","@id":"https:\/\/policyoptions.irpp.org\/fr\/#website","url":"https:\/\/policyoptions.irpp.org\/fr\/","name":"Policy Options","description":"Institute for Research on Public Policy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/policyoptions.irpp.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/issues\/265176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/issues"}],"about":[{"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/types\/issues"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/media\/253581"}],"wp:attachment":[{"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/media?parent=265176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/categories?post=265176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/tags?post=265176"},{"taxonomy":"article-status","embeddable":true,"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/article-status?post=265176"},{"taxonomy":"irpp-category","embeddable":true,"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/irpp-category?post=265176"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/section?post=265176"},{"taxonomy":"irpp-tag","embeddable":true,"href":"https:\/\/policyoptions.irpp.org\/fr\/wp-json\/wp\/v2\/irpp-tag?post=265176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}